
    {"id":99,"date":"2017-03-28T11:42:23","date_gmt":"2017-03-28T18:42:23","guid":{"rendered":"http:\/\/hesarizona.org\/glendale-charter-school\/?page_id=99"},"modified":"2025-10-03T09:27:55","modified_gmt":"2025-10-03T16:27:55","slug":"support","status":"publish","type":"page","link":"https:\/\/hesarizona.org\/glendale-charter-school\/support\/","title":{"rendered":"Support HES"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-99","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Support HES | Heritage Elementary Schools: Glendale | Glendale Charter School<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hesarizona.org\/glendale-charter-school\/support\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Support HES | Heritage Elementary Schools: Glendale | Glendale Charter School\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hesarizona.org\/glendale-charter-school\/support\/\" \/>\n<meta property=\"og:site_name\" content=\"Heritage Elementary Schools: Glendale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HESGlendale\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T16:27:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@hesglendale\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/support\\\/\",\"url\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/support\\\/\",\"name\":\"Support HES | Heritage Elementary Schools: Glendale | Glendale Charter School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/#website\"},\"datePublished\":\"2017-03-28T18:42:23+00:00\",\"dateModified\":\"2025-10-03T16:27:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/support\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/support\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/support\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Support HES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/#website\",\"url\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/\",\"name\":\"Heritage Elementary Schools: Glendale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Support HES | Heritage Elementary Schools: Glendale | Glendale Charter School","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hesarizona.org\/glendale-charter-school\/support\/","og_locale":"en_US","og_type":"article","og_title":"Support HES | Heritage Elementary Schools: Glendale | Glendale Charter School","og_url":"https:\/\/hesarizona.org\/glendale-charter-school\/support\/","og_site_name":"Heritage Elementary Schools: Glendale","article_publisher":"https:\/\/www.facebook.com\/HESGlendale","article_modified_time":"2025-10-03T16:27:55+00:00","twitter_card":"summary_large_image","twitter_site":"@hesglendale","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/support\/","url":"https:\/\/hesarizona.org\/glendale-charter-school\/support\/","name":"Support HES | Heritage Elementary Schools: Glendale | Glendale Charter School","isPartOf":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/#website"},"datePublished":"2017-03-28T18:42:23+00:00","dateModified":"2025-10-03T16:27:55+00:00","breadcrumb":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/support\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hesarizona.org\/glendale-charter-school\/support\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/support\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hesarizona.org\/glendale-charter-school\/"},{"@type":"ListItem","position":2,"name":"Support HES"}]},{"@type":"WebSite","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/#website","url":"https:\/\/hesarizona.org\/glendale-charter-school\/","name":"Heritage Elementary Schools: Glendale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hesarizona.org\/glendale-charter-school\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P8z59F-1B","_links":{"self":[{"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/pages\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/comments?post=99"}],"version-history":[{"count":0,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/pages\/99\/revisions"}],"wp:attachment":[{"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/media?parent=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}