
    {"id":8078,"date":"2018-04-27T08:55:10","date_gmt":"2018-04-27T15:55:10","guid":{"rendered":"http:\/\/hesarizona.org\/glendale-charter-school\/?p=8078"},"modified":"2018-04-27T08:55:10","modified_gmt":"2018-04-27T15:55:10","slug":"dont-miss-the-heritage-dance-choir-showcase","status":"publish","type":"post","link":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/","title":{"rendered":"Don&#8217;t Miss the Heritage Dance &#038; Choir Showcase"},"content":{"rendered":"<p>Join us on May 2 at 7 p.m. for our Dance &#038; Choir Showcase. Heritage students will sing and dance their way into your heart at this end-of-year extravaganza. Don&#8217;t miss this entertaining event.<\/p>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/04\/021149_HES_Glendale_DanceAndChoir.pdf\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/04\/021149_HES_Glendale_DanceAndChoir.jpg\" alt=\"Heritage Dance &#038; Choir Showcase\" width=\"612\" height=\"792\" class=\"aligncenter\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Join us on May 2 at 7 p.m. for our Dance &#038; Choir Showcase. Heritage students will sing and dance their way into your heart at this end-of-year extravaganza. Don&#8217;t miss this entertaining event.<\/p>\n","protected":false},"author":1,"featured_media":8080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-8078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-school-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Don&#039;t Miss the Heritage Dance &amp; Choir Showcase | Heritage Elementary Schools: Glendale | Glendale Charter School<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Don&#039;t Miss the Heritage Dance &amp; Choir Showcase | Heritage Elementary Schools: Glendale | Glendale Charter School\" \/>\n<meta property=\"og:description\" content=\"Join us on May 2 at 7 p.m. for our Dance &#038; Choir Showcase. Heritage students will sing and dance their way into your heart at this end-of-year extravaganza. Don&#8217;t miss this entertaining event.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/\" \/>\n<meta property=\"og:site_name\" content=\"Heritage Elementary Schools: Glendale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HESGlendale\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-27T15:55:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/04\/021149_HES_Glendale_DanceAndChoirFeatured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"online\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hesglendale\" \/>\n<meta name=\"twitter:site\" content=\"@hesglendale\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"online\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/dont-miss-the-heritage-dance-choir-showcase\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/dont-miss-the-heritage-dance-choir-showcase\\\/\"},\"author\":{\"name\":\"online\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/#\\\/schema\\\/person\\\/8012faf9fcc5e81dc52fa92abce2edda\"},\"headline\":\"Don&#8217;t Miss the Heritage Dance &#038; Choir Showcase\",\"datePublished\":\"2018-04-27T15:55:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/dont-miss-the-heritage-dance-choir-showcase\\\/\"},\"wordCount\":39,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/dont-miss-the-heritage-dance-choir-showcase\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/04\\\/021149_HES_Glendale_DanceAndChoirFeatured.jpg\",\"articleSection\":[\"School News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/dont-miss-the-heritage-dance-choir-showcase\\\/\",\"url\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/dont-miss-the-heritage-dance-choir-showcase\\\/\",\"name\":\"Don't Miss the Heritage Dance & Choir Showcase | Heritage Elementary Schools: Glendale | Glendale Charter School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/dont-miss-the-heritage-dance-choir-showcase\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/dont-miss-the-heritage-dance-choir-showcase\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/04\\\/021149_HES_Glendale_DanceAndChoirFeatured.jpg\",\"datePublished\":\"2018-04-27T15:55:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/#\\\/schema\\\/person\\\/8012faf9fcc5e81dc52fa92abce2edda\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/dont-miss-the-heritage-dance-choir-showcase\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/dont-miss-the-heritage-dance-choir-showcase\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/dont-miss-the-heritage-dance-choir-showcase\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/04\\\/021149_HES_Glendale_DanceAndChoirFeatured.jpg\",\"contentUrl\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/04\\\/021149_HES_Glendale_DanceAndChoirFeatured.jpg\",\"width\":800,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/dont-miss-the-heritage-dance-choir-showcase\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Don&#8217;t Miss the Heritage Dance &#038; Choir Showcase\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/#website\",\"url\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/\",\"name\":\"Heritage Elementary Schools: Glendale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/#\\\/schema\\\/person\\\/8012faf9fcc5e81dc52fa92abce2edda\",\"name\":\"online\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73698d91c4aa2ad301d36b687e35be2d49be3e7ba723c93023223c6da2e6d13b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73698d91c4aa2ad301d36b687e35be2d49be3e7ba723c93023223c6da2e6d13b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73698d91c4aa2ad301d36b687e35be2d49be3e7ba723c93023223c6da2e6d13b?s=96&d=mm&r=g\",\"caption\":\"online\"},\"url\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/author\\\/online\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Don't Miss the Heritage Dance & Choir Showcase | Heritage Elementary Schools: Glendale | Glendale Charter School","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/","og_locale":"en_US","og_type":"article","og_title":"Don't Miss the Heritage Dance & Choir Showcase | Heritage Elementary Schools: Glendale | Glendale Charter School","og_description":"Join us on May 2 at 7 p.m. for our Dance &#038; Choir Showcase. Heritage students will sing and dance their way into your heart at this end-of-year extravaganza. Don&#8217;t miss this entertaining event.","og_url":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/","og_site_name":"Heritage Elementary Schools: Glendale","article_publisher":"https:\/\/www.facebook.com\/HESGlendale","article_published_time":"2018-04-27T15:55:10+00:00","og_image":[{"width":800,"height":530,"url":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/04\/021149_HES_Glendale_DanceAndChoirFeatured.jpg","type":"image\/jpeg"}],"author":"online","twitter_card":"summary_large_image","twitter_creator":"@hesglendale","twitter_site":"@hesglendale","twitter_misc":{"Written by":"online"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/#article","isPartOf":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/"},"author":{"name":"online","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/#\/schema\/person\/8012faf9fcc5e81dc52fa92abce2edda"},"headline":"Don&#8217;t Miss the Heritage Dance &#038; Choir Showcase","datePublished":"2018-04-27T15:55:10+00:00","mainEntityOfPage":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/"},"wordCount":39,"commentCount":0,"image":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/#primaryimage"},"thumbnailUrl":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/04\/021149_HES_Glendale_DanceAndChoirFeatured.jpg","articleSection":["School News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/","url":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/","name":"Don't Miss the Heritage Dance & Choir Showcase | Heritage Elementary Schools: Glendale | Glendale Charter School","isPartOf":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/#primaryimage"},"image":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/#primaryimage"},"thumbnailUrl":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/04\/021149_HES_Glendale_DanceAndChoirFeatured.jpg","datePublished":"2018-04-27T15:55:10+00:00","author":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/#\/schema\/person\/8012faf9fcc5e81dc52fa92abce2edda"},"breadcrumb":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/#primaryimage","url":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/04\/021149_HES_Glendale_DanceAndChoirFeatured.jpg","contentUrl":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/04\/021149_HES_Glendale_DanceAndChoirFeatured.jpg","width":800,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/dont-miss-the-heritage-dance-choir-showcase\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hesarizona.org\/glendale-charter-school\/"},{"@type":"ListItem","position":2,"name":"Don&#8217;t Miss the Heritage Dance &#038; Choir Showcase"}]},{"@type":"WebSite","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/#website","url":"https:\/\/hesarizona.org\/glendale-charter-school\/","name":"Heritage Elementary Schools: Glendale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hesarizona.org\/glendale-charter-school\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/#\/schema\/person\/8012faf9fcc5e81dc52fa92abce2edda","name":"online","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/73698d91c4aa2ad301d36b687e35be2d49be3e7ba723c93023223c6da2e6d13b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/73698d91c4aa2ad301d36b687e35be2d49be3e7ba723c93023223c6da2e6d13b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73698d91c4aa2ad301d36b687e35be2d49be3e7ba723c93023223c6da2e6d13b?s=96&d=mm&r=g","caption":"online"},"url":"https:\/\/hesarizona.org\/glendale-charter-school\/author\/online\/"}]}},"jetpack_featured_media_url":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/04\/021149_HES_Glendale_DanceAndChoirFeatured.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8z59F-26i","_links":{"self":[{"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/posts\/8078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/comments?post=8078"}],"version-history":[{"count":0,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/posts\/8078\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/media\/8080"}],"wp:attachment":[{"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/media?parent=8078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/categories?post=8078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/tags?post=8078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}