
    {"id":8747,"date":"2018-08-20T09:11:57","date_gmt":"2018-08-20T16:11:57","guid":{"rendered":"http:\/\/hesarizona.org\/glendale-charter-school\/?p=8747"},"modified":"2018-08-20T09:11:57","modified_gmt":"2018-08-20T16:11:57","slug":"come-to-the-back-to-school-bash-concert","status":"publish","type":"post","link":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/","title":{"rendered":"Come to the Back-to-School Bash Concert"},"content":{"rendered":"<p>The Heritage Big Staff Band will perform at the free concert on the main field, Friday, August 24. Doors open at 6:30 p.m. with the show at 7 p.m. <\/p>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/08\/021489_HES_Glendale_Back-to-school_Bash_Flyer.pdf\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/08\/021489_HES_Glendale_Back-to-school_Bash_Flyer.jpg\" alt=\"Come to the Back-to-School Bash Concert\" width=\"630\" height=\"810\" class=\"aligncenter\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Heritage Big Staff Band will perform at the free concert on the main field, Friday, August 24. Doors open at 6:30 p.m. with the show at 7 p.m.<\/p>\n","protected":false},"author":1,"featured_media":8750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-8747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-school-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come to the Back-to-School Bash Concert | Heritage Elementary Schools: Glendale | Glendale Charter School<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come to the Back-to-School Bash Concert | Heritage Elementary Schools: Glendale | Glendale Charter School\" \/>\n<meta property=\"og:description\" content=\"The Heritage Big Staff Band will perform at the free concert on the main field, Friday, August 24. Doors open at 6:30 p.m. with the show at 7 p.m.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/\" \/>\n<meta property=\"og:site_name\" content=\"Heritage Elementary Schools: Glendale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HESGlendale\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-20T16:11:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/08\/021489_HES_Glendale_Back-to-school_Bash_Featured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"online\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hesglendale\" \/>\n<meta name=\"twitter:site\" content=\"@hesglendale\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"online\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/come-to-the-back-to-school-bash-concert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/come-to-the-back-to-school-bash-concert\\\/\"},\"author\":{\"name\":\"online\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/#\\\/schema\\\/person\\\/8012faf9fcc5e81dc52fa92abce2edda\"},\"headline\":\"Come to the Back-to-School Bash Concert\",\"datePublished\":\"2018-08-20T16:11:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/come-to-the-back-to-school-bash-concert\\\/\"},\"wordCount\":34,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/come-to-the-back-to-school-bash-concert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/08\\\/021489_HES_Glendale_Back-to-school_Bash_Featured.jpg\",\"articleSection\":[\"School News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/come-to-the-back-to-school-bash-concert\\\/\",\"url\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/come-to-the-back-to-school-bash-concert\\\/\",\"name\":\"Come to the Back-to-School Bash Concert | Heritage Elementary Schools: Glendale | Glendale Charter School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/come-to-the-back-to-school-bash-concert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/come-to-the-back-to-school-bash-concert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/08\\\/021489_HES_Glendale_Back-to-school_Bash_Featured.jpg\",\"datePublished\":\"2018-08-20T16:11:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/#\\\/schema\\\/person\\\/8012faf9fcc5e81dc52fa92abce2edda\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/come-to-the-back-to-school-bash-concert\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/come-to-the-back-to-school-bash-concert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/come-to-the-back-to-school-bash-concert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/08\\\/021489_HES_Glendale_Back-to-school_Bash_Featured.jpg\",\"contentUrl\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/08\\\/021489_HES_Glendale_Back-to-school_Bash_Featured.jpg\",\"width\":800,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/come-to-the-back-to-school-bash-concert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come to the Back-to-School Bash Concert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/#website\",\"url\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/\",\"name\":\"Heritage Elementary Schools: Glendale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/#\\\/schema\\\/person\\\/8012faf9fcc5e81dc52fa92abce2edda\",\"name\":\"online\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73698d91c4aa2ad301d36b687e35be2d49be3e7ba723c93023223c6da2e6d13b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73698d91c4aa2ad301d36b687e35be2d49be3e7ba723c93023223c6da2e6d13b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73698d91c4aa2ad301d36b687e35be2d49be3e7ba723c93023223c6da2e6d13b?s=96&d=mm&r=g\",\"caption\":\"online\"},\"url\":\"https:\\\/\\\/hesarizona.org\\\/glendale-charter-school\\\/author\\\/online\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come to the Back-to-School Bash Concert | Heritage Elementary Schools: Glendale | Glendale Charter School","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/","og_locale":"en_US","og_type":"article","og_title":"Come to the Back-to-School Bash Concert | Heritage Elementary Schools: Glendale | Glendale Charter School","og_description":"The Heritage Big Staff Band will perform at the free concert on the main field, Friday, August 24. Doors open at 6:30 p.m. with the show at 7 p.m.","og_url":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/","og_site_name":"Heritage Elementary Schools: Glendale","article_publisher":"https:\/\/www.facebook.com\/HESGlendale","article_published_time":"2018-08-20T16:11:57+00:00","og_image":[{"width":800,"height":530,"url":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/08\/021489_HES_Glendale_Back-to-school_Bash_Featured.jpg","type":"image\/jpeg"}],"author":"online","twitter_card":"summary_large_image","twitter_creator":"@hesglendale","twitter_site":"@hesglendale","twitter_misc":{"Written by":"online"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/#article","isPartOf":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/"},"author":{"name":"online","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/#\/schema\/person\/8012faf9fcc5e81dc52fa92abce2edda"},"headline":"Come to the Back-to-School Bash Concert","datePublished":"2018-08-20T16:11:57+00:00","mainEntityOfPage":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/"},"wordCount":34,"commentCount":0,"image":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/#primaryimage"},"thumbnailUrl":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/08\/021489_HES_Glendale_Back-to-school_Bash_Featured.jpg","articleSection":["School News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/","url":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/","name":"Come to the Back-to-School Bash Concert | Heritage Elementary Schools: Glendale | Glendale Charter School","isPartOf":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/#primaryimage"},"image":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/#primaryimage"},"thumbnailUrl":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/08\/021489_HES_Glendale_Back-to-school_Bash_Featured.jpg","datePublished":"2018-08-20T16:11:57+00:00","author":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/#\/schema\/person\/8012faf9fcc5e81dc52fa92abce2edda"},"breadcrumb":{"@id":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/#primaryimage","url":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/08\/021489_HES_Glendale_Back-to-school_Bash_Featured.jpg","contentUrl":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/08\/021489_HES_Glendale_Back-to-school_Bash_Featured.jpg","width":800,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/come-to-the-back-to-school-bash-concert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hesarizona.org\/glendale-charter-school\/"},{"@type":"ListItem","position":2,"name":"Come to the Back-to-School Bash Concert"}]},{"@type":"WebSite","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/#website","url":"https:\/\/hesarizona.org\/glendale-charter-school\/","name":"Heritage Elementary Schools: Glendale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hesarizona.org\/glendale-charter-school\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/hesarizona.org\/glendale-charter-school\/#\/schema\/person\/8012faf9fcc5e81dc52fa92abce2edda","name":"online","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/73698d91c4aa2ad301d36b687e35be2d49be3e7ba723c93023223c6da2e6d13b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/73698d91c4aa2ad301d36b687e35be2d49be3e7ba723c93023223c6da2e6d13b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73698d91c4aa2ad301d36b687e35be2d49be3e7ba723c93023223c6da2e6d13b?s=96&d=mm&r=g","caption":"online"},"url":"https:\/\/hesarizona.org\/glendale-charter-school\/author\/online\/"}]}},"jetpack_featured_media_url":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-content\/uploads\/sites\/5\/2018\/08\/021489_HES_Glendale_Back-to-school_Bash_Featured.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8z59F-2h5","_links":{"self":[{"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/posts\/8747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/comments?post=8747"}],"version-history":[{"count":0,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/posts\/8747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/media\/8750"}],"wp:attachment":[{"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/media?parent=8747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/categories?post=8747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hesarizona.org\/glendale-charter-school\/wp-json\/wp\/v2\/tags?post=8747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}